{"id":89595,"date":"2023-06-01T11:32:28","date_gmt":"2023-06-01T11:32:28","guid":{"rendered":"https:\/\/workplane.es\/portfolio\/illuminacio\/"},"modified":"2023-06-28T11:56:29","modified_gmt":"2023-06-28T11:56:29","slug":"illuminacio","status":"publish","type":"portfolio","link":"https:\/\/workplane.es\/ca\/portfolio\/illuminacio\/","title":{"rendered":"Il\u00b7luminaci\u00f3"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"89595\" class=\"elementor elementor-89595 elementor-75861\" data-elementor-post-type=\"portfolio\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-18b68ca5 elementor-section-content-middle elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"18b68ca5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2262f353\" data-id=\"2262f353\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47694f1 elementor-widget elementor-widget-heading\" data-id=\"47694f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Llums i... acci\u00f3! \n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26a1860d elementor-widget elementor-widget-heading\" data-id=\"26a1860d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">El sector de la il\u00b7luminaci\u00f3 \u00e9s una \u00e0rea que ens apassiona, llums de tota mena i projectes de millora de producte. No dubteu a consultar amb nosaltres, doncs aqu\u00ed nom\u00e9s us mostrem una mica.\n\n<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-56edffbf elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"56edffbf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-75e8f296\" data-id=\"75e8f296\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e14fddf elementor-widget elementor-widget-heading\" data-id=\"6e14fddf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Disseny de llums de la llar<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e7d5d93 elementor-widget elementor-widget-heading\" data-id=\"6e7d5d93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Projectes per a empreses com Simon, Lamp, Kamisafe, Yiyang; Shangping o la botiga en l\u00ednia Dengwu.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7449ca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7449ca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-21a364b8\" data-id=\"21a364b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7bacf1f elementor-widget elementor-widget-image-carousel\" data-id=\"7bacf1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;pause_on_hover&quot;:&quot;no&quot;,&quot;pause_on_interaction&quot;:&quot;no&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel d&#039;imatges\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-016.jpg\" alt=\"lumi-016\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-017.jpg\" alt=\"lumi-017\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-018.jpg\" alt=\"lumi-018\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-019.jpg\" alt=\"lumi-019\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-02.jpg\" alt=\"lumi-02\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-020.jpg\" alt=\"lumi-020\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-021.jpg\" alt=\"lumi-021\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 de 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-023.jpg\" alt=\"lumi-023\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 de 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-06.jpg\" alt=\"lumi-06\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 de 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-05.jpg\" alt=\"lumi-05\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 de 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-08.jpg\" alt=\"lumi-08\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 de 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-04.jpg\" alt=\"lumi-04\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 de 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-07.jpg\" alt=\"lumi-07\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 de 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-03.jpg\" alt=\"lumi-03\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 de 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-014.jpg\" alt=\"lumi-014\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 de 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-015.jpg\" alt=\"lumi-015\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73f3761e elementor-widget elementor-widget-heading\" data-id=\"73f3761e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Llums de taula\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbd8196 elementor-widget elementor-widget-heading\" data-id=\"cbd8196\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Llums de sobretaula, multifuncionals i pr\u00e0ctiques.\n\n \n \n \n \n \n \n \n \n \n \n \n \n \n<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cb10b5e elementor-widget elementor-widget-image-carousel\" data-id=\"6cb10b5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:&quot;3&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel d&#039;imatges\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-025.jpeg\" alt=\"lumi-025\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-026.jpeg\" alt=\"lumi-026\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-027.jpeg\" alt=\"Midea\u5fae\u6ce2\u7089\u7b56\u5212\u6848\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-028.jpeg\" alt=\"lumi-028\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17d51ae2 elementor-widget elementor-widget-image-carousel\" data-id=\"17d51ae2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:&quot;3&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;pause_on_hover&quot;:&quot;no&quot;,&quot;pause_on_interaction&quot;:&quot;no&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel d&#039;imatges\" dir=\"rtl\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-029.jpeg\" alt=\"lumi-029\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-030.jpeg\" alt=\"lumi-030\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-031.jpeg\" alt=\"lumi-031\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-032.jpeg\" alt=\"lumi-032\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-037.jpeg\" alt=\"lumi-037\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-036.jpeg\" alt=\"lumi-036\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-035.jpeg\" alt=\"lumi-035\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-46991fc\" data-id=\"46991fc\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64562688 elementor-widget elementor-widget-heading\" data-id=\"64562688\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">I no nom\u00e9s dissenyo...<br><br><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76a470ac elementor-widget elementor-widget-heading\" data-id=\"76a470ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Tamb\u00e9 oferim solucions d'enginyeria, aquest n'\u00e9s un exemple<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50d422d8 elementor-widget elementor-widget-image-carousel\" data-id=\"50d422d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel d&#039;imatges\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-049.jpeg\" alt=\"lumi-049\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-055.jpeg\" alt=\"lumi-055\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-046.jpeg\" alt=\"lumi-046\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-045.jpeg\" alt=\"lumi-045\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-054.jpeg\" alt=\"lumi-054\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-053.jpeg\" alt=\"lumi-053\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-050.jpeg\" alt=\"lumi-050\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 de 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-047.jpeg\" alt=\"lumi-047\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 de 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-048.jpeg\" alt=\"lumi-048\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 de 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-052.jpeg\" alt=\"lumi-052\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39c4079b elementor-widget elementor-widget-heading\" data-id=\"39c4079b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><b>L'any 2011<\/b> col\u00b7laborem amb l'empresa <b>LAMP,<\/b>\n<br><br>\n<b>Projecte:<\/b> Desenvolupant unes propostes de millora per als fanals urbans ECO i MINI ECO, adaptant components i complint les normatives vigents de PL segons la norma EN ISO 13849-1.\n<br><br>\n<b>Equip:<\/b> En aquest projecte realitzat \u00edntegrament a la nostra oficina de Barcelona, \u200b\u200bva requerir els perfils de: Cap de Projecte, 2 dissenyadors industrials i 1 enginyer mec\u00e0nic.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bf134f2 elementor-widget elementor-widget-image\" data-id=\"4bf134f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"280\" height=\"94\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/log-lumi-01.jpg\" class=\"attachment-full size-full wp-image-84305\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7795db22 elementor-blockquote--skin-quotation elementor-blockquote--align-left elementor-blockquote--button-color-official elementor-widget elementor-widget-blockquote\" data-id=\"7795db22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\tUna llum molt t\u00e8nue nom\u00e9s significa pocs fotons. Veure els electrons implica modificar-los.\n<br>\t\t\t<\/p>\n\t\t\t\t\t\t\t<div class=\"e-q-footer\">\n\t\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-blockquote__author\">Richard Phillips Feynman<\/cite>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-584de181 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"584de181\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-71c2822b\" data-id=\"71c2822b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f5b4a26 elementor-widget elementor-widget-heading\" data-id=\"1f5b4a26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Il\u00b7luminaci\u00f3 per a hospitals i centres sanitaris.\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32fc977c elementor-widget elementor-widget-heading\" data-id=\"32fc977c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Al sector salut \u00e9s una eina imprescidible.\n<br><br>\nLlums que combinen llum brillant o un ambient c\u00e0lid i acollidor.\nEstem compromesos a oferir les millors solucions d'il\u00b7luminaci\u00f3 LED per a interiors per a aplicacions d'atenci\u00f3 m\u00e8dica. Reconeixem la import\u00e0ncia de les solucions sostenibles que brinden als centres d'atenci\u00f3 m\u00e8dica il\u00b7luminaci\u00f3 d'alta qualitat i d'efici\u00e8ncia energ\u00e8tica.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2515ee3e elementor-widget elementor-widget-image-carousel\" data-id=\"2515ee3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;pause_on_hover&quot;:&quot;no&quot;,&quot;pause_on_interaction&quot;:&quot;no&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel d&#039;imatges\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-038.jpeg\" alt=\"lumi-038\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-040.jpeg\" alt=\"lumi-040\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-039.jpeg\" alt=\"lumi-039\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6cfd8175 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6cfd8175\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-635aa78a\" data-id=\"635aa78a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18100824 elementor-widget elementor-widget-image\" data-id=\"18100824\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"360\" height=\"269\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-043.jpeg\" class=\"attachment-full size-full wp-image-84326\" alt=\"\" srcset=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-043.jpeg 360w, https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-043-300x224.jpeg 300w, https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-043-350x262.jpeg 350w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-2d68b8d1\" data-id=\"2d68b8d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15447a0d elementor-widget elementor-widget-image\" data-id=\"15447a0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"360\" height=\"269\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-044.jpeg\" class=\"attachment-full size-full wp-image-84329\" alt=\"\" srcset=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-044.jpeg 360w, https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-044-300x224.jpeg 300w, https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-044-350x262.jpeg 350w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-5f5a147\" data-id=\"5f5a147\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c9e63b2 elementor-widget elementor-widget-image\" data-id=\"1c9e63b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"269\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-041.jpeg\" class=\"attachment-full size-full wp-image-84335\" alt=\"\" srcset=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-041.jpeg 360w, https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-041-300x224.jpeg 300w, https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-041-350x262.jpeg 350w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-460d814c\" data-id=\"460d814c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fe12202 elementor-widget elementor-widget-image\" data-id=\"5fe12202\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"269\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-042.jpeg\" class=\"attachment-full size-full wp-image-84332\" alt=\"\" srcset=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-042.jpeg 360w, https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-042-300x224.jpeg 300w, https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-042-350x262.jpeg 350w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-7dcbdf77 elementor-widget elementor-widget-heading\" data-id=\"7dcbdf77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Els colors depenen de la llum que un veu\n<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4db9e21d elementor-widget elementor-widget-heading\" data-id=\"4db9e21d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Qualsevol espai necessita una llum adaptada a aquest.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e909fe2 elementor-widget elementor-widget-image-carousel\" data-id=\"5e909fe2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel d&#039;imatges\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-060.jpeg\" alt=\"lumi-060\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-064.jpeg\" alt=\"lumi-064\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-061.jpg\" alt=\"lumi-061\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-063.jpeg\" alt=\"lumi-063\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-059.jpeg\" alt=\"lumi-059\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-058.jpeg\" alt=\"lumi-058\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-057.jpeg\" alt=\"lumi-057\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-062.jpeg\" alt=\"lumi-062\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1971c4e4 elementor-widget elementor-widget-heading\" data-id=\"1971c4e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Un llum sol tenir una vida \u00fatil de diversos anys, de vegades fins a d\u00e8cades i el disseny no pot ser passatger.\n<br><br>\n\u00d2bviament, no adaptem als estils sol\u00b7licitats pels nostres clients. Cl\u00e0ssic, Modern, Inusual, minimalista, exclusiu\u2026<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5336cd22 elementor-widget elementor-widget-heading\" data-id=\"5336cd22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dissenys atemporals<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48bcd6d9 elementor-widget elementor-widget-heading\" data-id=\"48bcd6d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Un llum sol tenir una vida \u00fatil de diversos anys, de vegades fins a d\u00e8cades i el disseny no pot ser passatger\n<br><br>\n\u00d2bviament, ens adaptem als estils sol\u00b7licitats pels nostres clients. Cl\u00e0ssic, Modern, Inusual, minimalista, exclusiu\u2026<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d148914 elementor-widget elementor-widget-image-carousel\" data-id=\"6d148914\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;2&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;pause_on_hover&quot;:&quot;no&quot;,&quot;pause_on_interaction&quot;:&quot;no&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:9,&quot;sizes&quot;:[]},&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel d&#039;imatges\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-010.png\" alt=\"lumi-010\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-011.png\" alt=\"lumi-011\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-013.png\" alt=\"lumi-013\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/lumi-012.png\" alt=\"lumi-012\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-589f4a00 elementor-hidden-tablet\" data-id=\"589f4a00\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b7d06ca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b7d06ca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6e7284b1\" data-id=\"6e7284b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7127ef19 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7127ef19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/workplane.es\/contacto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Si la teva empresa pot estar interessada en un projecte similar CONTACTA'NS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e793154 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e793154\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6507c40\" data-id=\"6507c40\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c593da8 elementor-widget elementor-widget-shortcode\" data-id=\"c593da8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"89904\" class=\"elementor elementor-89904 elementor-86165\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-41a88e8 elementor-section-content-middle elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"41a88e8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bcb546e\" data-id=\"bcb546e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-650ad53 elementor-widget elementor-widget-heading\" data-id=\"650ad53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Altres projectes<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2281f7f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2281f7f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-582d963\" data-id=\"582d963\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-956853d elementor-posts--align-center elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"956853d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;3&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-89648 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-conceptualitzacio-ca portfolio_category-corporate-image-ca portfolio_category-engineering-ca portfolio_category-product-design-ca portfolio_category-technical-products-ca portfolio_category-user-experience-ca\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/workplane.es\/ca\/portfolio\/audio-streamer\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"799\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/05\/af-Magic-Sound-Audio-Device8.jpg\" class=\"attachment-full size-full wp-image-86342\" alt=\"\" srcset=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/05\/af-Magic-Sound-Audio-Device8.jpg 2560w, https:\/\/workplane.es\/wp-content\/uploads\/2023\/05\/af-Magic-Sound-Audio-Device8-300x94.jpg 300w, https:\/\/workplane.es\/wp-content\/uploads\/2023\/05\/af-Magic-Sound-Audio-Device8-1024x320.jpg 1024w, https:\/\/workplane.es\/wp-content\/uploads\/2023\/05\/af-Magic-Sound-Audio-Device8-768x240.jpg 768w, https:\/\/workplane.es\/wp-content\/uploads\/2023\/05\/af-Magic-Sound-Audio-Device8-1536x479.jpg 1536w, https:\/\/workplane.es\/wp-content\/uploads\/2023\/05\/af-Magic-Sound-Audio-Device8-2048x639.jpg 2048w, https:\/\/workplane.es\/wp-content\/uploads\/2023\/05\/af-Magic-Sound-Audio-Device8-350x109.jpg 350w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h4 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/workplane.es\/ca\/portfolio\/audio-streamer\/\" >\n\t\t\t\t\u00c0udio Streamer\t\t\t<\/a>\n\t\t<\/h4>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Winner of a IF Design Award 2019. Magic Sound is \u00c0udio Streamer que executes more than 33 sounds.  <\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-89644 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-conceptualitzacio portfolio_category-disseny-de-producte portfolio_category-electrodomestics portfolio_category-end-to-end-ca\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/workplane.es\/ca\/portfolio\/aspiradora-augewei\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"800\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/portada-aspi26.jpg\" class=\"attachment-full size-full wp-image-81831\" alt=\"\" srcset=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/portada-aspi26.jpg 2560w, https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/portada-aspi26-300x94.jpg 300w, https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/portada-aspi26-1024x320.jpg 1024w, https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/portada-aspi26-768x240.jpg 768w, https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/portada-aspi26-1536x480.jpg 1536w, https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/portada-aspi26-2048x640.jpg 2048w, https:\/\/workplane.es\/wp-content\/uploads\/2023\/04\/portada-aspi26-350x109.jpg 350w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h4 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/workplane.es\/ca\/portfolio\/aspiradora-augewei\/\" >\n\t\t\t\tAspiradora AUGEWEI\t\t\t<\/a>\n\t\t<\/h4>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>L&#8217;aspiradora tipus trineu per a Augewei, \u00e9s un altre projecte que podem catalogar com un exemple de servei \u201cend to end\u201d Doncs hem participat activament en totes les fases del seu desenvolupament.<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-89640 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-conceptualitzacio portfolio_category-disseny-de-producte portfolio_category-llar\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/workplane.es\/ca\/portfolio\/accessoris-de-bany\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"800\" src=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/02\/WP-Weidushi_z-series-copy.jpg\" class=\"attachment-full size-full wp-image-79897\" alt=\"\" srcset=\"https:\/\/workplane.es\/wp-content\/uploads\/2023\/02\/WP-Weidushi_z-series-copy.jpg 2560w, https:\/\/workplane.es\/wp-content\/uploads\/2023\/02\/WP-Weidushi_z-series-copy-300x94.jpg 300w, https:\/\/workplane.es\/wp-content\/uploads\/2023\/02\/WP-Weidushi_z-series-copy-1024x320.jpg 1024w, https:\/\/workplane.es\/wp-content\/uploads\/2023\/02\/WP-Weidushi_z-series-copy-768x240.jpg 768w, https:\/\/workplane.es\/wp-content\/uploads\/2023\/02\/WP-Weidushi_z-series-copy-1536x480.jpg 1536w, https:\/\/workplane.es\/wp-content\/uploads\/2023\/02\/WP-Weidushi_z-series-copy-2048x640.jpg 2048w, https:\/\/workplane.es\/wp-content\/uploads\/2023\/02\/WP-Weidushi_z-series-copy-350x109.jpg 350w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h4 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/workplane.es\/ca\/portfolio\/accessoris-de-bany\/\" >\n\t\t\t\tAccessoris de bany\t\t\t<\/a>\n\t\t<\/h4>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Els bons accessoris no destaquen entre la decoraci\u00f3 i queden integrats a la vida de la llar.<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b9928a elementor-align-center elementor-widget elementor-widget-button\" data-id=\"9b9928a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/workplane.es\/work\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">TREBALLS DESTACATS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>El sector de la il\u00b7luminaci\u00f3 \u00e9s una \u00e0rea que ens apassiona, llums de tota mena i projectes de millora de producte. No dubteu a consultar amb nosaltres, doncs aqu\u00ed nom\u00e9s us mostrem una mica.<\/p>\n","protected":false},"author":1,"featured_media":81064,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_theme","meta":{"content-type":"","footnotes":""},"portfolio_category":[287,286,288],"class_list":["post-89595","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_category-conceptualitzacio","portfolio_category-disseny-de-producte","portfolio_category-illuminacio"],"_links":{"self":[{"href":"https:\/\/workplane.es\/ca\/wp-json\/wp\/v2\/portfolio\/89595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/workplane.es\/ca\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/workplane.es\/ca\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/workplane.es\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/workplane.es\/ca\/wp-json\/wp\/v2\/comments?post=89595"}],"version-history":[{"count":3,"href":"https:\/\/workplane.es\/ca\/wp-json\/wp\/v2\/portfolio\/89595\/revisions"}],"predecessor-version":[{"id":90038,"href":"https:\/\/workplane.es\/ca\/wp-json\/wp\/v2\/portfolio\/89595\/revisions\/90038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/workplane.es\/ca\/wp-json\/wp\/v2\/media\/81064"}],"wp:attachment":[{"href":"https:\/\/workplane.es\/ca\/wp-json\/wp\/v2\/media?parent=89595"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/workplane.es\/ca\/wp-json\/wp\/v2\/portfolio_category?post=89595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}